{"id":802,"date":"2018-09-23T17:32:36","date_gmt":"2018-09-23T17:32:36","guid":{"rendered":"http:\/\/www.familien-fuer-familien.eu\/?post_type=tribe_events&#038;p=802"},"modified":"2018-09-23T17:32:36","modified_gmt":"2018-09-23T17:32:36","slug":"inca-und-familien-fuer-familien-feiern-froehliches-sommerfest-mit-tanzen-spielen-und-musizieren","status":"publish","type":"tribe_events","link":"http:\/\/www.familien-fuer-familien.eu\/en\/termin\/inca-und-familien-fuer-familien-feiern-froehliches-sommerfest-mit-tanzen-spielen-und-musizieren\/","title":{"rendered":"INCA und Familien f\u00fcr Familien feiern fr\u00f6hliches Sommerfest mit Tanzen, Spielen und Musizieren"},"content":{"rendered":"<p>Sonnenschein im Gemeindehaus der Friedenskirche: Unter dem Motto \u201eSINGEN \u2013 TANZEN \u2013 LACHEN \u2013 SPIELEN \u2013 MUSIZIEREN\u201c haben INCA und Familien f\u00fcr Familien zum gemeinsamen Sommerfest eingeladen. Es sollte f\u00fcr jede Altersgruppe Spa\u00df dabei sein: Spiele f\u00fcr die kleinen, Aktionen f\u00fcr die Jugend und interessante Gespr\u00e4che f\u00fcr die Eltern. Herausgekommen ist ein wundersch\u00f6ner Freitagnachmittag: Etwa 200 G\u00e4ste verbrachten etwa 3 Stunden bei sonnigen Wetter im Garten des Gemeindehauses.<\/p>\n<p>H\u00f6hepunkte war zum einem die Livemusik von \u201eSax\u2018 O Chor\u201c aus Salzgitter mit sieben Saxofonen bzw. sechs Saxofonen und einer Klarinette \u2013 so wurden alte Klassiker von den Beatles und andere bekannte Melodien gespielt.\u00a0 Zum anderen waren die Auftritte der weiblichen russischen T\u00e4nzer sehr berauschend, die erst traditionelle russische T\u00e4nze und danach orientalisches Bauchtanzen vorf\u00fchrten. F\u00fcr diese Auftritte gab es sehr viel Applaus.<\/p>\n<p><a href=\"http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2018\/09\/Fest.jpg\" data-rel=\"lightbox-image-0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-803\" src=\"http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2018\/09\/Fest-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2018\/09\/Fest-300x225.jpg 300w, http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2018\/09\/Fest-768x576.jpg 768w, http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2018\/09\/Fest.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2018\/09\/Saxofon.jpg\" data-rel=\"lightbox-image-1\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-804\" src=\"http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2018\/09\/Saxofon-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2018\/09\/Saxofon-300x225.jpg 300w, http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2018\/09\/Saxofon-768x576.jpg 768w, http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2018\/09\/Saxofon.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2018\/09\/Tanzen.jpg\" data-rel=\"lightbox-image-2\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-805\" src=\"http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2018\/09\/Tanzen-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2018\/09\/Tanzen-300x225.jpg 300w, http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2018\/09\/Tanzen-768x576.jpg 768w, http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2018\/09\/Tanzen.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>F\u00fcr die kleinen Kinder war die gro\u00dfe H\u00fcpfburg der H\u00f6hepunkt \u2013 sie freuten sich aber auch \u00fcber den Jongleur, der beim Jonglieren erst seine B\u00e4lle essen wollte, dann jedoch eine Paprika verschlang. Parallel konnten sich alle G\u00e4ste beim Buffet st\u00e4rken, lachen und sich austauschen. Hier standen das nahende Eulenfest, aber auch Nachfragen zu den Dingen des Alltags im Vordergrund. F\u00fcr viele Familien, die seit 1-3 Jahren in Deutschland leben, sind z.B. Schreiben von Schulen und von den Beh\u00f6rden nicht leicht zu verstehen. Auch die Anmeldungen zum Mittagessen in den Schulen stellen eine gro\u00dfe H\u00fcrde dar und sind ohne umfassendere Deutschkenntnisse kaum alleine auszuf\u00fcllen. Die Vermittlung von Praktika und Arbeit ist f\u00fcr viele Frauen und M\u00e4nner das gro\u00dfe Ziel. Daher gibt es hierzu immer wieder viele Fragen und Austauschgespr\u00e4che. Hier kann das gemeinsame Netzwerk genutzt werden, das immer wieder auf andere Partnerinnen und Partner verweisen kann.<\/p>\n<p>Jessica Hauk, die neue Verantwortliche vom INCA war nach dem Fest v\u00f6llig begeistert: \u201eDie Atmosph\u00e4re heute war wundersch\u00f6n und friedlich. Durch die wunderbare Musik ist eine unglaublich sch\u00f6ne Stimmung entstanden \u2013 alle G\u00e4ste sahen heute sehr entspannt und gl\u00fccklich aus.\u201c Auch Andrea Friedrich von Familien von Familien betont: \u201eIch habe mich insbesondere gefreut, dass alle mit anfassen beim Aufbau und beim Abbau, um ein so sch\u00f6nes Fest zu feiern. Als die letzten 10 Aktiven zum Festende zufrieden im aufger\u00e4umten Gemeindehaus standen, wurde schnell beschlossen, den Abend gemeinsam in der Peiner Innenstadt ausklingen zu lassen.<\/p>\n<p>Und es geht weiter! Das \u201eINCA\u201c findet auch den n\u00e4chsten Wochen regelm\u00e4\u00dfig statt: Jeder Freitag von 15 bis 17 Uhr sind alle Peiner herzlich eingeladen ins Gemeindehaus der Friedenskirche, Eichendorffstr. 6. INCA beinhaltet sehr viele Angebote &#8211; vom Caf\u00e9, Reisen, Lass Wachsen bis zum N\u00e4hNett und wird in Kooperation mit Ev.-luth. Kirchenkreis Peine, Diakonischen Werk des Ev.-luth. Kirchenkreisverbandes Hildesheim und der Friedenskirchengemeinde Peine organisiert.<\/p>\n<p>Familien f\u00fcr Familien freut sich auf die n\u00e4chsten Feste im Gemeinschaftsgarten \u2013 zum Erntefest werden G\u00e4ste und Interessierte eingeladen. Termine sind aktuell noch in der Abstimmung und k\u00f6nnen bei <a href=\"mailto:familien-fuer-familien@gmx.de\">familien-fuer-familien@gmx.de<\/a> nachgefragt und auf der Homepage nachgelesen werden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sonnenschein im Gemeindehaus der Friedenskirche: Unter dem Motto \u201eSINGEN \u2013 TANZEN \u2013 LACHEN \u2013 SPIELEN \u2013 MUSIZIEREN\u201c haben INCA und Familien f\u00fcr Familien zum gemeinsamen Sommerfest eingeladen. Es sollte f\u00fcr jede Altersgruppe Spa\u00df dabei sein: Spiele f\u00fcr die kleinen, Aktionen f\u00fcr die Jugend und interessante Gespr\u00e4che f\u00fcr die Eltern. Herausgekommen ist ein wundersch\u00f6ner Freitagnachmittag: Etwa [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-802","tribe_events","type-tribe_events","status-publish","czr-hentry"],"translation":{"provider":"WPGlobus","version":"3.0.1","language":"en","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>INCA und Familien f\u00fcr Familien feiern fr\u00f6hliches Sommerfest mit Tanzen, Spielen und Musizieren - Familien f\u00fcr Familien e.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.familien-fuer-familien.eu\/termin\/inca-und-familien-fuer-familien-feiern-froehliches-sommerfest-mit-tanzen-spielen-und-musizieren\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"INCA und Familien f\u00fcr Familien feiern fr\u00f6hliches Sommerfest mit Tanzen, Spielen und Musizieren - Familien f\u00fcr Familien e.V.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.familien-fuer-familien.eu\/termin\/inca-und-familien-fuer-familien-feiern-froehliches-sommerfest-mit-tanzen-spielen-und-musizieren\/\" \/>\n<meta property=\"og:site_name\" content=\"Familien f\u00fcr Familien e.V.\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2018\/09\/Fest-300x225.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.familien-fuer-familien.eu\/termin\/inca-und-familien-fuer-familien-feiern-froehliches-sommerfest-mit-tanzen-spielen-und-musizieren\/\",\"url\":\"http:\/\/www.familien-fuer-familien.eu\/termin\/inca-und-familien-fuer-familien-feiern-froehliches-sommerfest-mit-tanzen-spielen-und-musizieren\/\",\"name\":\"INCA und Familien f\u00fcr Familien feiern fr\u00f6hliches Sommerfest mit Tanzen, Spielen und Musizieren - Familien f\u00fcr Familien e.V.\",\"isPartOf\":{\"@id\":\"http:\/\/www.familien-fuer-familien.eu\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.familien-fuer-familien.eu\/termin\/inca-und-familien-fuer-familien-feiern-froehliches-sommerfest-mit-tanzen-spielen-und-musizieren\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/www.familien-fuer-familien.eu\/termin\/inca-und-familien-fuer-familien-feiern-froehliches-sommerfest-mit-tanzen-spielen-und-musizieren\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2018\/09\/Fest-300x225.jpg\",\"datePublished\":\"2018-09-23T17:32:36+00:00\",\"dateModified\":\"2018-09-23T17:32:36+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/www.familien-fuer-familien.eu\/termin\/inca-und-familien-fuer-familien-feiern-froehliches-sommerfest-mit-tanzen-spielen-und-musizieren\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.familien-fuer-familien.eu\/termin\/inca-und-familien-fuer-familien-feiern-froehliches-sommerfest-mit-tanzen-spielen-und-musizieren\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\/\/www.familien-fuer-familien.eu\/termin\/inca-und-familien-fuer-familien-feiern-froehliches-sommerfest-mit-tanzen-spielen-und-musizieren\/#primaryimage\",\"url\":\"http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2018\/09\/Fest-300x225.jpg\",\"contentUrl\":\"http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2018\/09\/Fest-300x225.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.familien-fuer-familien.eu\/termin\/inca-und-familien-fuer-familien-feiern-froehliches-sommerfest-mit-tanzen-spielen-und-musizieren\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/www.familien-fuer-familien.eu\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"http:\/\/www.familien-fuer-familien.eu\/en\/termine\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"INCA und Familien f\u00fcr Familien feiern fr\u00f6hliches Sommerfest mit Tanzen, Spielen und Musizieren\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.familien-fuer-familien.eu\/en\/#website\",\"url\":\"http:\/\/www.familien-fuer-familien.eu\/en\/\",\"name\":\"Familien f\u00fcr Familien e.V.\",\"description\":\"Arriving is just the start - we continue\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/www.familien-fuer-familien.eu\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"INCA und Familien f\u00fcr Familien feiern fr\u00f6hliches Sommerfest mit Tanzen, Spielen und Musizieren - Familien f\u00fcr Familien e.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.familien-fuer-familien.eu\/termin\/inca-und-familien-fuer-familien-feiern-froehliches-sommerfest-mit-tanzen-spielen-und-musizieren\/","og_locale":"en_US","og_type":"article","og_title":"INCA und Familien f\u00fcr Familien feiern fr\u00f6hliches Sommerfest mit Tanzen, Spielen und Musizieren - Familien f\u00fcr Familien e.V.","og_url":"http:\/\/www.familien-fuer-familien.eu\/termin\/inca-und-familien-fuer-familien-feiern-froehliches-sommerfest-mit-tanzen-spielen-und-musizieren\/","og_site_name":"Familien f\u00fcr Familien e.V.","og_image":[{"url":"http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2018\/09\/Fest-300x225.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.familien-fuer-familien.eu\/termin\/inca-und-familien-fuer-familien-feiern-froehliches-sommerfest-mit-tanzen-spielen-und-musizieren\/","url":"http:\/\/www.familien-fuer-familien.eu\/termin\/inca-und-familien-fuer-familien-feiern-froehliches-sommerfest-mit-tanzen-spielen-und-musizieren\/","name":"INCA und Familien f\u00fcr Familien feiern fr\u00f6hliches Sommerfest mit Tanzen, Spielen und Musizieren - Familien f\u00fcr Familien e.V.","isPartOf":{"@id":"http:\/\/www.familien-fuer-familien.eu\/en\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.familien-fuer-familien.eu\/termin\/inca-und-familien-fuer-familien-feiern-froehliches-sommerfest-mit-tanzen-spielen-und-musizieren\/#primaryimage"},"image":{"@id":"http:\/\/www.familien-fuer-familien.eu\/termin\/inca-und-familien-fuer-familien-feiern-froehliches-sommerfest-mit-tanzen-spielen-und-musizieren\/#primaryimage"},"thumbnailUrl":"http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2018\/09\/Fest-300x225.jpg","datePublished":"2018-09-23T17:32:36+00:00","dateModified":"2018-09-23T17:32:36+00:00","breadcrumb":{"@id":"http:\/\/www.familien-fuer-familien.eu\/termin\/inca-und-familien-fuer-familien-feiern-froehliches-sommerfest-mit-tanzen-spielen-und-musizieren\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.familien-fuer-familien.eu\/termin\/inca-und-familien-fuer-familien-feiern-froehliches-sommerfest-mit-tanzen-spielen-und-musizieren\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/www.familien-fuer-familien.eu\/termin\/inca-und-familien-fuer-familien-feiern-froehliches-sommerfest-mit-tanzen-spielen-und-musizieren\/#primaryimage","url":"http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2018\/09\/Fest-300x225.jpg","contentUrl":"http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2018\/09\/Fest-300x225.jpg"},{"@type":"BreadcrumbList","@id":"http:\/\/www.familien-fuer-familien.eu\/termin\/inca-und-familien-fuer-familien-feiern-froehliches-sommerfest-mit-tanzen-spielen-und-musizieren\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/www.familien-fuer-familien.eu\/en\/"},{"@type":"ListItem","position":2,"name":"Events","item":"http:\/\/www.familien-fuer-familien.eu\/en\/termine\/"},{"@type":"ListItem","position":3,"name":"INCA und Familien f\u00fcr Familien feiern fr\u00f6hliches Sommerfest mit Tanzen, Spielen und Musizieren"}]},{"@type":"WebSite","@id":"http:\/\/www.familien-fuer-familien.eu\/en\/#website","url":"http:\/\/www.familien-fuer-familien.eu\/en\/","name":"Familien f\u00fcr Familien e.V.","description":"Arriving is just the start - we continue","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.familien-fuer-familien.eu\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"http:\/\/www.familien-fuer-familien.eu\/en\/wp-json\/wp\/v2\/tribe_events\/802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.familien-fuer-familien.eu\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"http:\/\/www.familien-fuer-familien.eu\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"http:\/\/www.familien-fuer-familien.eu\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.familien-fuer-familien.eu\/en\/wp-json\/wp\/v2\/comments?post=802"}],"version-history":[{"count":2,"href":"http:\/\/www.familien-fuer-familien.eu\/en\/wp-json\/wp\/v2\/tribe_events\/802\/revisions"}],"predecessor-version":[{"id":807,"href":"http:\/\/www.familien-fuer-familien.eu\/en\/wp-json\/wp\/v2\/tribe_events\/802\/revisions\/807"}],"wp:attachment":[{"href":"http:\/\/www.familien-fuer-familien.eu\/en\/wp-json\/wp\/v2\/media?parent=802"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.familien-fuer-familien.eu\/en\/wp-json\/wp\/v2\/tags?post=802"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"http:\/\/www.familien-fuer-familien.eu\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}