{"id":2208,"date":"2024-01-02T11:42:34","date_gmt":"2024-01-02T11:42:34","guid":{"rendered":"http:\/\/www.familien-fuer-familien.eu\/?p=2208"},"modified":"2024-01-02T11:46:00","modified_gmt":"2024-01-02T11:46:00","slug":"inca-und-familien-fuer-familien-unterwegs-wissenschaft-und-spass-am-leben-und-lernen-im-phano-wolfsburg","status":"publish","type":"post","link":"https:\/\/www.familien-fuer-familien.eu\/en\/inca-und-familien-fuer-familien-unterwegs-wissenschaft-und-spass-am-leben-und-lernen-im-phano-wolfsburg\/","title":{"rendered":"<strong>INCA und Familien f\u00fcr Familien unterwegs &#8211;<br>Wissenschaft und Spa\u00df am Leben und Lernen im Phano Wolfsburg<\/strong>"},"content":{"rendered":"\n<p>Nach dem Ausflug nach Thale im Harz und dem Zoo Hannover ging der dritte Ausflug an einen grauen regnerischen Novembertag Phaeno in Wolfsburg.\u00a0 Inca (Internationales Cafe) und Familien f\u00fcr Familien organisierten wieder gemeinsam den wundersch\u00f6nen Ausflug und waren begeistert \u00fcber die hohe Nachfrage und die wundersch\u00f6ne Zeit beim Besuch des Wissenschaftsmuseum.<\/p>\n<p>145 Kleine Wissenschaftler und neugierig<a href=\"http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2024\/01\/20231111_101020736_iOS.jpg\" data-rel=\"lightbox-image-0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2210 alignleft\" src=\"http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2024\/01\/20231111_101020736_iOS-300x225.jpg\" alt=\"\" width=\"847\" height=\"635\" srcset=\"https:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2024\/01\/20231111_101020736_iOS-300x225.jpg 300w, https:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2024\/01\/20231111_101020736_iOS-768x576.jpg 768w, https:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2024\/01\/20231111_101020736_iOS.jpg 1024w\" sizes=\"auto, (max-width: 847px) 100vw, 847px\" \/><\/a> <a href=\"http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2024\/01\/20231111_105713605_iOS.jpg\" data-rel=\"lightbox-image-1\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-2211 alignleft\" src=\"http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2024\/01\/20231111_105713605_iOS-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2024\/01\/20231111_105713605_iOS-300x225.jpg 300w, https:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2024\/01\/20231111_105713605_iOS-768x576.jpg 768w, https:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2024\/01\/20231111_105713605_iOS.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> gebliebene Erwachsene staunten \u00fcber Ph\u00e4nomene aus Natur, Wissenschaft und Technik. Experimente, Installationen, Wissenschaftsshows zu den Themen Leben, Sehen, Energie, Dynamik, Sp\u00fcrsinn, Mathematik beeindruckten die Teilnehmer nachhaltig. Der bis zu 6 Meter hohe Feuertornado faszinierte vor allem die kleinen G\u00e4ste. Menschen unterschiedlichster Herkunft erlebten gemeinsam, dass Physik und Mathematik \u00fcberall auf der Welt den gleichen Naturgesetzen unterliegen. In vielen kleinen wechselnden Gruppen spielten, lernen und lachten gro\u00dfe und kleine Kinder und erkl\u00e4rten sich gegenseitig die sch\u00f6nen Ph\u00e4nomene.<\/p>\n<p>In der Mittagspause beim gemeinsamen Picknick, kam auch der Austausch und das leibliche Wohl nicht zu kurz. Dort war Zeit, sich auszutauschen, zu reflektieren und die n\u00e4chsten Aktionen zu planen. Alle hatten viel Spa\u00df dabei und haben sogar etwas f\u00fcrs Leben gelernt.<\/p>\n<p>Zum Jahresabschluss gibt es viele sch\u00f6ne Aktionen im INCA \u2013 jeden Freitag 15-17:30 Uhr im Gemeindehaus der Friedenskirche. Sehr gut angenommen wird das neue Gestaltungsangebot f\u00fcr Frauen und Kinder von Jessica Feer. Der finale H\u00f6hepunkt ist auch dieses Jahr das Weihnachtsfest am 15.12. mit gemeinsamem Singen und einem Weihnachtsmann \u2013 dieses Jahr in einer neuen Verkleidung!<\/p>\n<p>INCA und Familien f\u00fcr Familien wollen sich ganz herzlich bei den vielen Helfern bedanken, die Woche f\u00fcr Woche unglaublich wertvolle Arbeit geleistet haben. Riesendank an die vielen gro\u00dfartigen Helfer!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nach dem Ausflug nach Thale im Harz und dem Zoo Hannover ging der dritte Ausflug an einen grauen regnerischen Novembertag Phaeno in Wolfsburg.\u00a0 Inca (Internationales Cafe) und Familien f\u00fcr Familien organisierten wieder gemeinsam den wundersch\u00f6nen Ausflug und waren begeistert \u00fcber die hohe Nachfrage und die wundersch\u00f6ne Zeit beim Besuch des Wissenschaftsmuseum. 145 Kleine Wissenschaftler und [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-2208","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-news","7":"czr-hentry"},"translation":{"provider":"WPGlobus","version":"3.0.1","language":"en","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>INCA und Familien f\u00fcr Familien unterwegs -Wissenschaft und Spa\u00df am Leben und Lernen im Phano Wolfsburg - Familien f\u00fcr Familien e.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.familien-fuer-familien.eu\/en\/inca-und-familien-fuer-familien-unterwegs-wissenschaft-und-spass-am-leben-und-lernen-im-phano-wolfsburg\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"INCA und Familien f\u00fcr Familien unterwegs -Wissenschaft und Spa\u00df am Leben und Lernen im Phano Wolfsburg - Familien f\u00fcr Familien e.V.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.familien-fuer-familien.eu\/en\/inca-und-familien-fuer-familien-unterwegs-wissenschaft-und-spass-am-leben-und-lernen-im-phano-wolfsburg\/\" \/>\n<meta property=\"og:site_name\" content=\"Familien f\u00fcr Familien e.V.\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-02T11:42:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-02T11:46:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2024\/01\/20231111_101020736_iOS-300x225.jpg\" \/>\n<meta name=\"author\" content=\"HenningMeyer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"HenningMeyer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.familien-fuer-familien.eu\/en\/inca-und-familien-fuer-familien-unterwegs-wissenschaft-und-spass-am-leben-und-lernen-im-phano-wolfsburg\/\",\"url\":\"https:\/\/www.familien-fuer-familien.eu\/en\/inca-und-familien-fuer-familien-unterwegs-wissenschaft-und-spass-am-leben-und-lernen-im-phano-wolfsburg\/\",\"name\":\"INCA und Familien f\u00fcr Familien unterwegs - Wissenschaft und Spa\u00df am Leben und Lernen im Phano Wolfsburg - Familien f\u00fcr Familien e.V.\",\"isPartOf\":{\"@id\":\"http:\/\/www.familien-fuer-familien.eu\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.familien-fuer-familien.eu\/en\/inca-und-familien-fuer-familien-unterwegs-wissenschaft-und-spass-am-leben-und-lernen-im-phano-wolfsburg\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.familien-fuer-familien.eu\/en\/inca-und-familien-fuer-familien-unterwegs-wissenschaft-und-spass-am-leben-und-lernen-im-phano-wolfsburg\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2024\/01\/20231111_101020736_iOS-300x225.jpg\",\"datePublished\":\"2024-01-02T11:42:34+00:00\",\"dateModified\":\"2024-01-02T11:46:00+00:00\",\"author\":{\"@id\":\"http:\/\/www.familien-fuer-familien.eu\/en\/#\/schema\/person\/23e04a046102a1baecb71b50c3caca26\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.familien-fuer-familien.eu\/en\/inca-und-familien-fuer-familien-unterwegs-wissenschaft-und-spass-am-leben-und-lernen-im-phano-wolfsburg\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.familien-fuer-familien.eu\/en\/inca-und-familien-fuer-familien-unterwegs-wissenschaft-und-spass-am-leben-und-lernen-im-phano-wolfsburg\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.familien-fuer-familien.eu\/en\/inca-und-familien-fuer-familien-unterwegs-wissenschaft-und-spass-am-leben-und-lernen-im-phano-wolfsburg\/#primaryimage\",\"url\":\"http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2024\/01\/20231111_101020736_iOS-300x225.jpg\",\"contentUrl\":\"http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2024\/01\/20231111_101020736_iOS-300x225.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.familien-fuer-familien.eu\/en\/inca-und-familien-fuer-familien-unterwegs-wissenschaft-und-spass-am-leben-und-lernen-im-phano-wolfsburg\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/www.familien-fuer-familien.eu\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"INCA und Familien f\u00fcr Familien unterwegs &#8211;Wissenschaft und Spa\u00df am Leben und Lernen im Phano Wolfsburg\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.familien-fuer-familien.eu\/en\/#website\",\"url\":\"http:\/\/www.familien-fuer-familien.eu\/en\/\",\"name\":\"Familien f\u00fcr Familien e.V.\",\"description\":\"Arriving is just the start - we continue\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/www.familien-fuer-familien.eu\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"http:\/\/www.familien-fuer-familien.eu\/en\/#\/schema\/person\/23e04a046102a1baecb71b50c3caca26\",\"name\":\"HenningMeyer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\/\/www.familien-fuer-familien.eu\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b7139956b4d2c7fdfea93e1f19239547326b327c54444f46d20638e041823ac3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b7139956b4d2c7fdfea93e1f19239547326b327c54444f46d20638e041823ac3?s=96&d=mm&r=g\",\"caption\":\"HenningMeyer\"},\"url\":\"https:\/\/www.familien-fuer-familien.eu\/en\/author\/henningmeyer\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"INCA und Familien f\u00fcr Familien unterwegs -Wissenschaft und Spa\u00df am Leben und Lernen im Phano Wolfsburg - Familien f\u00fcr Familien e.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.familien-fuer-familien.eu\/en\/inca-und-familien-fuer-familien-unterwegs-wissenschaft-und-spass-am-leben-und-lernen-im-phano-wolfsburg\/","og_locale":"en_US","og_type":"article","og_title":"INCA und Familien f\u00fcr Familien unterwegs -Wissenschaft und Spa\u00df am Leben und Lernen im Phano Wolfsburg - Familien f\u00fcr Familien e.V.","og_url":"https:\/\/www.familien-fuer-familien.eu\/en\/inca-und-familien-fuer-familien-unterwegs-wissenschaft-und-spass-am-leben-und-lernen-im-phano-wolfsburg\/","og_site_name":"Familien f\u00fcr Familien e.V.","article_published_time":"2024-01-02T11:42:34+00:00","article_modified_time":"2024-01-02T11:46:00+00:00","og_image":[{"url":"http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2024\/01\/20231111_101020736_iOS-300x225.jpg"}],"author":"HenningMeyer","twitter_card":"summary_large_image","twitter_misc":{"Written by":"HenningMeyer","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.familien-fuer-familien.eu\/en\/inca-und-familien-fuer-familien-unterwegs-wissenschaft-und-spass-am-leben-und-lernen-im-phano-wolfsburg\/","url":"https:\/\/www.familien-fuer-familien.eu\/en\/inca-und-familien-fuer-familien-unterwegs-wissenschaft-und-spass-am-leben-und-lernen-im-phano-wolfsburg\/","name":"INCA und Familien f\u00fcr Familien unterwegs - Wissenschaft und Spa\u00df am Leben und Lernen im Phano Wolfsburg - Familien f\u00fcr Familien e.V.","isPartOf":{"@id":"http:\/\/www.familien-fuer-familien.eu\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.familien-fuer-familien.eu\/en\/inca-und-familien-fuer-familien-unterwegs-wissenschaft-und-spass-am-leben-und-lernen-im-phano-wolfsburg\/#primaryimage"},"image":{"@id":"https:\/\/www.familien-fuer-familien.eu\/en\/inca-und-familien-fuer-familien-unterwegs-wissenschaft-und-spass-am-leben-und-lernen-im-phano-wolfsburg\/#primaryimage"},"thumbnailUrl":"http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2024\/01\/20231111_101020736_iOS-300x225.jpg","datePublished":"2024-01-02T11:42:34+00:00","dateModified":"2024-01-02T11:46:00+00:00","author":{"@id":"http:\/\/www.familien-fuer-familien.eu\/en\/#\/schema\/person\/23e04a046102a1baecb71b50c3caca26"},"breadcrumb":{"@id":"https:\/\/www.familien-fuer-familien.eu\/en\/inca-und-familien-fuer-familien-unterwegs-wissenschaft-und-spass-am-leben-und-lernen-im-phano-wolfsburg\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.familien-fuer-familien.eu\/en\/inca-und-familien-fuer-familien-unterwegs-wissenschaft-und-spass-am-leben-und-lernen-im-phano-wolfsburg\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.familien-fuer-familien.eu\/en\/inca-und-familien-fuer-familien-unterwegs-wissenschaft-und-spass-am-leben-und-lernen-im-phano-wolfsburg\/#primaryimage","url":"http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2024\/01\/20231111_101020736_iOS-300x225.jpg","contentUrl":"http:\/\/www.familien-fuer-familien.eu\/wp-content\/uploads\/2024\/01\/20231111_101020736_iOS-300x225.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.familien-fuer-familien.eu\/en\/inca-und-familien-fuer-familien-unterwegs-wissenschaft-und-spass-am-leben-und-lernen-im-phano-wolfsburg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/www.familien-fuer-familien.eu\/en\/"},{"@type":"ListItem","position":2,"name":"INCA und Familien f\u00fcr Familien unterwegs &#8211;Wissenschaft und Spa\u00df am Leben und Lernen im Phano Wolfsburg"}]},{"@type":"WebSite","@id":"http:\/\/www.familien-fuer-familien.eu\/en\/#website","url":"http:\/\/www.familien-fuer-familien.eu\/en\/","name":"Familien f\u00fcr Familien e.V.","description":"Arriving is just the start - we continue","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.familien-fuer-familien.eu\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Person","@id":"http:\/\/www.familien-fuer-familien.eu\/en\/#\/schema\/person\/23e04a046102a1baecb71b50c3caca26","name":"HenningMeyer","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/www.familien-fuer-familien.eu\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b7139956b4d2c7fdfea93e1f19239547326b327c54444f46d20638e041823ac3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b7139956b4d2c7fdfea93e1f19239547326b327c54444f46d20638e041823ac3?s=96&d=mm&r=g","caption":"HenningMeyer"},"url":"https:\/\/www.familien-fuer-familien.eu\/en\/author\/henningmeyer\/"}]}},"_links":{"self":[{"href":"https:\/\/www.familien-fuer-familien.eu\/en\/wp-json\/wp\/v2\/posts\/2208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.familien-fuer-familien.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.familien-fuer-familien.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.familien-fuer-familien.eu\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.familien-fuer-familien.eu\/en\/wp-json\/wp\/v2\/comments?post=2208"}],"version-history":[{"count":2,"href":"https:\/\/www.familien-fuer-familien.eu\/en\/wp-json\/wp\/v2\/posts\/2208\/revisions"}],"predecessor-version":[{"id":2214,"href":"https:\/\/www.familien-fuer-familien.eu\/en\/wp-json\/wp\/v2\/posts\/2208\/revisions\/2214"}],"wp:attachment":[{"href":"https:\/\/www.familien-fuer-familien.eu\/en\/wp-json\/wp\/v2\/media?parent=2208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.familien-fuer-familien.eu\/en\/wp-json\/wp\/v2\/categories?post=2208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.familien-fuer-familien.eu\/en\/wp-json\/wp\/v2\/tags?post=2208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}